{"id":251199,"date":"2024-02-04T11:57:32","date_gmt":"2024-02-04T16:57:32","guid":{"rendered":"https:\/\/paju.org\/?p=251199"},"modified":"2024-02-04T12:07:29","modified_gmt":"2024-02-04T17:07:29","slug":"la-controverse-autour-de-lunited-nations-relief-and-works-agency-unrwa-devie-lattention-de-la-crise-humanitaire-a-gaza","status":"publish","type":"post","link":"https:\/\/paju.org\/fr\/la-controverse-autour-de-lunited-nations-relief-and-works-agency-unrwa-devie-lattention-de-la-crise-humanitaire-a-gaza\/","title":{"rendered":"La\u00a0controverse autour de l&rsquo;United Nations Relief and Works Agency (UNRWA) d\u00e9vie l&rsquo;attention de la crise humanitaire \u00e0 Gaza"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>TRTFRAN\u00c7AIS<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Une vingtaine d\u2019Organisations Non Gouvernementales (ONG), dont Oxfam et M\u00e9decins Du Monde (MDM), ont \u00e9crit qu\u2019elles \u00e9taient choqu\u00e9es et r\u00e9volt\u00e9es par la d\u00e9cision irresponsable d\u2019une douzaine de pays de couper les vivres \u00e0 une population tout enti\u00e8re.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00ab&nbsp;Les activit\u00e9s criminelles ne doivent jamais rester impunies, mais la discussion actuelle ne fait que d\u00e9tourner l&rsquo;attention de ce qui se passe r\u00e9ellement chaque jour, chaque heure et chaque minute, \u00e0 Gaza. N&rsquo;oublions pas quels sont les vrais probl\u00e8mes sur le terrain&nbsp;\u00bb, a d\u00e9clar\u00e9 un porte-parole de l&rsquo;Organisation Mondiale de la Sant\u00e9 (OMS), Christian Lindmeier, lors d&rsquo;un point de presse r\u00e9gulier \u00e0 Gen\u00e8ve.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Au m\u00eame moment, le minist\u00e8re de la sant\u00e9 de Gaza a annonc\u00e9 que le bilan des victimes palestiniennes de l&rsquo;offensive isra\u00e9lienne meurtri\u00e8re \u00e0 Gaza depuis le samedi 7 octobre 2023 est de plus de vingt-six mille sept cent cinquante morts.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Une douzaine de pays ont annonc\u00e9 qu\u2019ils suspendaient leur financement \u00e0 l&rsquo;UNRWA apr\u00e8s les accusations isra\u00e9liennes selon lesquelles certains employ\u00e9s seraient impliqu\u00e9s dans les attaques du samedi 7 octobre 2023.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Christian Lindmeier a rappel\u00e9 que le directeur g\u00e9n\u00e9ral de l&rsquo;OMS, Tedros Adhanom Ghebreyesus, avait appel\u00e9 les donateurs \u00e0 ne pas suspendre leur financement \u00e0 l&rsquo;UNWRA en ce moment tr\u00e8s critique, car cela ne fera que nuire \u00e0 la population de Gaza qui a d\u00e9sesp\u00e9r\u00e9ment besoin d&rsquo;aide.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00ab&nbsp;Cela d\u00e9tourne l&rsquo;attention du fait qu&rsquo;une population enti\u00e8re est emp\u00each\u00e9e d&rsquo;avoir acc\u00e8s \u00e0 l&rsquo;eau potable, \u00e0 la nourriture et \u00e0 des abris. Cela d\u00e9tourne l&rsquo;attention du fait que l&rsquo;\u00e9lectricit\u00e9 est emp\u00each\u00e9e d&rsquo;arriver \u00e0 Gaza depuis plus d\u2019une centaine de jours&nbsp;\u00bb, a dit Christian Lindmeier.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Une vingtaine d&rsquo;ONG internationales ont \u00e9crit qu\u2019elles \u00e9taient r\u00e9volt\u00e9es par la suspension du financement alors que Gaza vit une situation de catastrophe humanitaire.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00ab&nbsp;L&rsquo;UNWRA est le principal fournisseur d&rsquo;aide \u00e0 Gaza et dans la r\u00e9gion et cesser de la financer va avoir une incidence sur l&rsquo;aide vitale apport\u00e9e \u00e0 plus de deux millions de civils, dont plus de la moiti\u00e9 sont des enfants, qui d\u00e9pendent tous de son aide&nbsp;\u00bb, \u00e9crivent vingt-et-une ONG, dont Oxfam, MDM, Save the Children et le Danish Refugee Council, dans un communiqu\u00e9 commun.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Elles se disent choqu\u00e9es par la d\u00e9cision irresponsable des bailleurs de couper les vivres \u00e0 une population tout enti\u00e8re, alors que ces pays appelaient eux-m\u00eames au renforcement de l\u2019aide \u00e0 Gaza, \u00ab&nbsp;nous sommes profond\u00e9ment pr\u00e9occup\u00e9es et r\u00e9volt\u00e9es par le fait que certains des principaux donateurs aient convenu de suspendre leurs financements \u00e0 l&rsquo;UNWRA, alors que la catastrophe humanitaire empire de jour en jour \u00e0 Gaza. Les autres agences pr\u00e9sentes \u00e0 Gaza ne pouvant pas remplacer l&rsquo;aide humanitaire de l\u2019UNRWA, si les suspensions de financement sont maintenues, nous risquons d&rsquo;assister \u00e0 l&rsquo;effondrement total de la r\u00e9ponse humanitaire, d\u00e9j\u00e0 tr\u00e8s limit\u00e9e, \u00e0 Gaza. Nous demandons aux pays concern\u00e9s d\u2019annuler la suspension de leur financement \u00e0 l&rsquo;UNWRA&nbsp;\u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Rami Abdo, chef de l&rsquo;Observatoire Europ\u00e9en des Droits Humains (OEDH), a d\u00e9clar\u00e9 qu&rsquo;Isra\u00ebl utilise la faim comme une arme pour d\u00e9placer les habitants de Gaza et m\u00eame pour les tuer, expliquant que Gaza souffre d&rsquo;une grave p\u00e9nurie de vivres et que le flux de l&rsquo;aide qui arrive quotidiennement a diminu\u00e9 de cinq cents camions avant la guerre \u00e0 moins d\u2019une centaine de camions actuellement, \u00ab&nbsp;plus de la moiti\u00e9 des palestiniens de Gaza souffre d&rsquo;une faim extr\u00eame. Tous les habitants du nord de Gaza sont confront\u00e9s \u00e0 de graves conditions de famine&nbsp;\u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Il a indiqu\u00e9 que les soldats de l&rsquo;occupation avaient ouvert le feu contre les palestiniens qui tentaient d&rsquo;atteindre les camions de nourriture qui entraient en petit nombre \u00e0 Gaza du sud vers le nord et que l\u2019OEDH avait document\u00e9 la mort de dizaines de palestiniens \u00e0 cause de cela, \u00ab&nbsp;nous parlons d&rsquo;une famine d\u00e9lib\u00e9r\u00e9e, en particulier dans le nord de Gaza, et les enfants sont les plus touch\u00e9s par cette situation&nbsp;\u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/www.trtfrancais.com\/actualites\/oms-la-controverse-autour-de-lunrwa-devie-lattention-de-la-crise-humanitaire-a-gaza-16799584\">https:\/\/www.trtfrancais.com\/actualites\/oms-la-controverse-autour-de-lunrwa-devie-lattention-de-la-crise-humanitaire-a-gaza-16799584<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Une vingtaine d\u2019Organisations Non Gouvernementales (ONG), dont Oxfam et M\u00e9decins Du Monde (MDM), ont \u00e9crit qu\u2019elles \u00e9taient choqu\u00e9es et r\u00e9volt\u00e9es par la d\u00e9cision irresponsable d\u2019une douzaine de pays de couper les vivres \u00e0 une population tout enti\u00e8re<\/p>\n","protected":false},"author":4,"featured_media":251196,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[94],"tags":[],"class_list":["post-251199","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-bulletin-fr"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La\u00a0controverse autour de l&#039;United Nations Relief and Works Agency (UNRWA) d\u00e9vie l&#039;attention de la crise humanitaire \u00e0 Gaza - PAJU<\/title>\n<meta name=\"description\" content=\"Une vingtaine d\u2019Organisations Non Gouvernementales (ONG), dont Oxfam et M\u00e9decins Du Monde (MDM), ont \u00e9crit qu\u2019elles \u00e9taient choqu\u00e9es et r\u00e9volt\u00e9es par la d\u00e9cision irresponsable d\u2019une douzaine de pays de couper les vivres \u00e0 une population tout enti\u00e8re.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/paju.org\/fr\/la-controverse-autour-de-lunited-nations-relief-and-works-agency-unrwa-devie-lattention-de-la-crise-humanitaire-a-gaza\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La\u00a0controverse autour de l&#039;United Nations Relief and Works Agency (UNRWA) d\u00e9vie l&#039;attention de la crise humanitaire \u00e0 Gaza - PAJU\" \/>\n<meta property=\"og:description\" content=\"Une vingtaine d\u2019Organisations Non Gouvernementales (ONG), dont Oxfam et M\u00e9decins Du Monde (MDM), ont \u00e9crit qu\u2019elles \u00e9taient choqu\u00e9es et r\u00e9volt\u00e9es par la d\u00e9cision irresponsable d\u2019une douzaine de pays de couper les vivres \u00e0 une population tout enti\u00e8re.\" \/>\n<meta property=\"og:site_name\" content=\"PAJU\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/pajumontreal\" \/>\n<meta property=\"article:published_time\" content=\"2024-02-04T16:57:32+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-02-04T17:07:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/paju.org\/wp-content\/uploads\/Les-Palestiniens-de-Gaza-luttent-contre-la-famine-Photo-AA-AA.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"720\" \/>\n\t<meta property=\"og:image:height\" content=\"405\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Bruce Katz\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Bruce Katz\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/paju.org\\\/fr\\\/la-controverse-autour-de-lunited-nations-relief-and-works-agency-unrwa-devie-lattention-de-la-crise-humanitaire-a-gaza\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/paju.org\\\/fr\\\/la-controverse-autour-de-lunited-nations-relief-and-works-agency-unrwa-devie-lattention-de-la-crise-humanitaire-a-gaza\\\/\"},\"author\":{\"name\":\"Bruce Katz\",\"@id\":\"https:\\\/\\\/paju.org\\\/fr\\\/#\\\/schema\\\/person\\\/6d8aed1579a1f4a97e1c552a5f2a891d\"},\"headline\":\"La\u00a0controverse autour de l&rsquo;United Nations Relief and Works Agency (UNRWA) d\u00e9vie l&rsquo;attention de la crise humanitaire \u00e0 Gaza\",\"datePublished\":\"2024-02-04T16:57:32+00:00\",\"dateModified\":\"2024-02-04T17:07:29+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/paju.org\\\/fr\\\/la-controverse-autour-de-lunited-nations-relief-and-works-agency-unrwa-devie-lattention-de-la-crise-humanitaire-a-gaza\\\/\"},\"wordCount\":745,\"publisher\":{\"@id\":\"https:\\\/\\\/paju.org\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/paju.org\\\/fr\\\/la-controverse-autour-de-lunited-nations-relief-and-works-agency-unrwa-devie-lattention-de-la-crise-humanitaire-a-gaza\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/paju.org\\\/wp-content\\\/uploads\\\/Les-Palestiniens-de-Gaza-luttent-contre-la-famine-Photo-AA-AA.jpeg\",\"articleSection\":[\"Notre bulletin\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/paju.org\\\/fr\\\/la-controverse-autour-de-lunited-nations-relief-and-works-agency-unrwa-devie-lattention-de-la-crise-humanitaire-a-gaza\\\/\",\"url\":\"https:\\\/\\\/paju.org\\\/fr\\\/la-controverse-autour-de-lunited-nations-relief-and-works-agency-unrwa-devie-lattention-de-la-crise-humanitaire-a-gaza\\\/\",\"name\":\"La\u00a0controverse autour de l'United Nations Relief and Works Agency (UNRWA) d\u00e9vie l'attention de la crise humanitaire \u00e0 Gaza - PAJU\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/paju.org\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/paju.org\\\/fr\\\/la-controverse-autour-de-lunited-nations-relief-and-works-agency-unrwa-devie-lattention-de-la-crise-humanitaire-a-gaza\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/paju.org\\\/fr\\\/la-controverse-autour-de-lunited-nations-relief-and-works-agency-unrwa-devie-lattention-de-la-crise-humanitaire-a-gaza\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/paju.org\\\/wp-content\\\/uploads\\\/Les-Palestiniens-de-Gaza-luttent-contre-la-famine-Photo-AA-AA.jpeg\",\"datePublished\":\"2024-02-04T16:57:32+00:00\",\"dateModified\":\"2024-02-04T17:07:29+00:00\",\"description\":\"Une vingtaine d\u2019Organisations Non Gouvernementales (ONG), dont Oxfam et M\u00e9decins Du Monde (MDM), ont \u00e9crit qu\u2019elles \u00e9taient choqu\u00e9es et r\u00e9volt\u00e9es par la d\u00e9cision irresponsable d\u2019une douzaine de pays de couper les vivres \u00e0 une population tout enti\u00e8re.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/paju.org\\\/fr\\\/la-controverse-autour-de-lunited-nations-relief-and-works-agency-unrwa-devie-lattention-de-la-crise-humanitaire-a-gaza\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/paju.org\\\/fr\\\/la-controverse-autour-de-lunited-nations-relief-and-works-agency-unrwa-devie-lattention-de-la-crise-humanitaire-a-gaza\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/paju.org\\\/fr\\\/la-controverse-autour-de-lunited-nations-relief-and-works-agency-unrwa-devie-lattention-de-la-crise-humanitaire-a-gaza\\\/#primaryimage\",\"url\":\"https:\\\/\\\/paju.org\\\/wp-content\\\/uploads\\\/Les-Palestiniens-de-Gaza-luttent-contre-la-famine-Photo-AA-AA.jpeg\",\"contentUrl\":\"https:\\\/\\\/paju.org\\\/wp-content\\\/uploads\\\/Les-Palestiniens-de-Gaza-luttent-contre-la-famine-Photo-AA-AA.jpeg\",\"width\":720,\"height\":405},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/paju.org\\\/fr\\\/la-controverse-autour-de-lunited-nations-relief-and-works-agency-unrwa-devie-lattention-de-la-crise-humanitaire-a-gaza\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/paju.org\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La\u00a0controverse autour de l&#8217;United Nations Relief and Works Agency (UNRWA) d\u00e9vie l&#8217;attention de la crise humanitaire \u00e0 Gaza\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/paju.org\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/paju.org\\\/fr\\\/\",\"name\":\"PAJU\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/paju.org\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/paju.org\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/paju.org\\\/fr\\\/#organization\",\"name\":\"Palestinian and Jewish Unity\",\"url\":\"https:\\\/\\\/paju.org\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/paju.org\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/paju.org\\\/wp-content\\\/uploads\\\/PAJU-Logo.png\",\"contentUrl\":\"https:\\\/\\\/paju.org\\\/wp-content\\\/uploads\\\/PAJU-Logo.png\",\"width\":696,\"height\":293,\"caption\":\"Palestinian and Jewish Unity\"},\"image\":{\"@id\":\"https:\\\/\\\/paju.org\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/pajumontreal\",\"https:\\\/\\\/www.instagram.com\\\/pajumontreal\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/paju.org\\\/fr\\\/#\\\/schema\\\/person\\\/6d8aed1579a1f4a97e1c552a5f2a891d\",\"name\":\"Bruce Katz\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c65b2117dbb672d0bda009f0367a4721c9271f1f68b1747fb53d7333079d0f1?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c65b2117dbb672d0bda009f0367a4721c9271f1f68b1747fb53d7333079d0f1?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c65b2117dbb672d0bda009f0367a4721c9271f1f68b1747fb53d7333079d0f1?s=96&d=mm&r=g\",\"caption\":\"Bruce Katz\"},\"url\":\"https:\\\/\\\/paju.org\\\/fr\\\/author\\\/chadi\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La\u00a0controverse autour de l'United Nations Relief and Works Agency (UNRWA) d\u00e9vie l'attention de la crise humanitaire \u00e0 Gaza - PAJU","description":"Une vingtaine d\u2019Organisations Non Gouvernementales (ONG), dont Oxfam et M\u00e9decins Du Monde (MDM), ont \u00e9crit qu\u2019elles \u00e9taient choqu\u00e9es et r\u00e9volt\u00e9es par la d\u00e9cision irresponsable d\u2019une douzaine de pays de couper les vivres \u00e0 une population tout enti\u00e8re.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/paju.org\/fr\/la-controverse-autour-de-lunited-nations-relief-and-works-agency-unrwa-devie-lattention-de-la-crise-humanitaire-a-gaza\/","og_locale":"fr_FR","og_type":"article","og_title":"La\u00a0controverse autour de l'United Nations Relief and Works Agency (UNRWA) d\u00e9vie l'attention de la crise humanitaire \u00e0 Gaza - PAJU","og_description":"Une vingtaine d\u2019Organisations Non Gouvernementales (ONG), dont Oxfam et M\u00e9decins Du Monde (MDM), ont \u00e9crit qu\u2019elles \u00e9taient choqu\u00e9es et r\u00e9volt\u00e9es par la d\u00e9cision irresponsable d\u2019une douzaine de pays de couper les vivres \u00e0 une population tout enti\u00e8re.","og_site_name":"PAJU","article_publisher":"https:\/\/www.facebook.com\/pajumontreal","article_published_time":"2024-02-04T16:57:32+00:00","article_modified_time":"2024-02-04T17:07:29+00:00","og_image":[{"width":720,"height":405,"url":"https:\/\/paju.org\/wp-content\/uploads\/Les-Palestiniens-de-Gaza-luttent-contre-la-famine-Photo-AA-AA.jpeg","type":"image\/jpeg"}],"author":"Bruce Katz","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Bruce Katz","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/paju.org\/fr\/la-controverse-autour-de-lunited-nations-relief-and-works-agency-unrwa-devie-lattention-de-la-crise-humanitaire-a-gaza\/#article","isPartOf":{"@id":"https:\/\/paju.org\/fr\/la-controverse-autour-de-lunited-nations-relief-and-works-agency-unrwa-devie-lattention-de-la-crise-humanitaire-a-gaza\/"},"author":{"name":"Bruce Katz","@id":"https:\/\/paju.org\/fr\/#\/schema\/person\/6d8aed1579a1f4a97e1c552a5f2a891d"},"headline":"La\u00a0controverse autour de l&rsquo;United Nations Relief and Works Agency (UNRWA) d\u00e9vie l&rsquo;attention de la crise humanitaire \u00e0 Gaza","datePublished":"2024-02-04T16:57:32+00:00","dateModified":"2024-02-04T17:07:29+00:00","mainEntityOfPage":{"@id":"https:\/\/paju.org\/fr\/la-controverse-autour-de-lunited-nations-relief-and-works-agency-unrwa-devie-lattention-de-la-crise-humanitaire-a-gaza\/"},"wordCount":745,"publisher":{"@id":"https:\/\/paju.org\/fr\/#organization"},"image":{"@id":"https:\/\/paju.org\/fr\/la-controverse-autour-de-lunited-nations-relief-and-works-agency-unrwa-devie-lattention-de-la-crise-humanitaire-a-gaza\/#primaryimage"},"thumbnailUrl":"https:\/\/paju.org\/wp-content\/uploads\/Les-Palestiniens-de-Gaza-luttent-contre-la-famine-Photo-AA-AA.jpeg","articleSection":["Notre bulletin"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/paju.org\/fr\/la-controverse-autour-de-lunited-nations-relief-and-works-agency-unrwa-devie-lattention-de-la-crise-humanitaire-a-gaza\/","url":"https:\/\/paju.org\/fr\/la-controverse-autour-de-lunited-nations-relief-and-works-agency-unrwa-devie-lattention-de-la-crise-humanitaire-a-gaza\/","name":"La\u00a0controverse autour de l'United Nations Relief and Works Agency (UNRWA) d\u00e9vie l'attention de la crise humanitaire \u00e0 Gaza - PAJU","isPartOf":{"@id":"https:\/\/paju.org\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/paju.org\/fr\/la-controverse-autour-de-lunited-nations-relief-and-works-agency-unrwa-devie-lattention-de-la-crise-humanitaire-a-gaza\/#primaryimage"},"image":{"@id":"https:\/\/paju.org\/fr\/la-controverse-autour-de-lunited-nations-relief-and-works-agency-unrwa-devie-lattention-de-la-crise-humanitaire-a-gaza\/#primaryimage"},"thumbnailUrl":"https:\/\/paju.org\/wp-content\/uploads\/Les-Palestiniens-de-Gaza-luttent-contre-la-famine-Photo-AA-AA.jpeg","datePublished":"2024-02-04T16:57:32+00:00","dateModified":"2024-02-04T17:07:29+00:00","description":"Une vingtaine d\u2019Organisations Non Gouvernementales (ONG), dont Oxfam et M\u00e9decins Du Monde (MDM), ont \u00e9crit qu\u2019elles \u00e9taient choqu\u00e9es et r\u00e9volt\u00e9es par la d\u00e9cision irresponsable d\u2019une douzaine de pays de couper les vivres \u00e0 une population tout enti\u00e8re.","breadcrumb":{"@id":"https:\/\/paju.org\/fr\/la-controverse-autour-de-lunited-nations-relief-and-works-agency-unrwa-devie-lattention-de-la-crise-humanitaire-a-gaza\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/paju.org\/fr\/la-controverse-autour-de-lunited-nations-relief-and-works-agency-unrwa-devie-lattention-de-la-crise-humanitaire-a-gaza\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/paju.org\/fr\/la-controverse-autour-de-lunited-nations-relief-and-works-agency-unrwa-devie-lattention-de-la-crise-humanitaire-a-gaza\/#primaryimage","url":"https:\/\/paju.org\/wp-content\/uploads\/Les-Palestiniens-de-Gaza-luttent-contre-la-famine-Photo-AA-AA.jpeg","contentUrl":"https:\/\/paju.org\/wp-content\/uploads\/Les-Palestiniens-de-Gaza-luttent-contre-la-famine-Photo-AA-AA.jpeg","width":720,"height":405},{"@type":"BreadcrumbList","@id":"https:\/\/paju.org\/fr\/la-controverse-autour-de-lunited-nations-relief-and-works-agency-unrwa-devie-lattention-de-la-crise-humanitaire-a-gaza\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/paju.org\/fr\/"},{"@type":"ListItem","position":2,"name":"La\u00a0controverse autour de l&#8217;United Nations Relief and Works Agency (UNRWA) d\u00e9vie l&#8217;attention de la crise humanitaire \u00e0 Gaza"}]},{"@type":"WebSite","@id":"https:\/\/paju.org\/fr\/#website","url":"https:\/\/paju.org\/fr\/","name":"PAJU","description":"","publisher":{"@id":"https:\/\/paju.org\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/paju.org\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/paju.org\/fr\/#organization","name":"Palestinian and Jewish Unity","url":"https:\/\/paju.org\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/paju.org\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/paju.org\/wp-content\/uploads\/PAJU-Logo.png","contentUrl":"https:\/\/paju.org\/wp-content\/uploads\/PAJU-Logo.png","width":696,"height":293,"caption":"Palestinian and Jewish Unity"},"image":{"@id":"https:\/\/paju.org\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/pajumontreal","https:\/\/www.instagram.com\/pajumontreal\/"]},{"@type":"Person","@id":"https:\/\/paju.org\/fr\/#\/schema\/person\/6d8aed1579a1f4a97e1c552a5f2a891d","name":"Bruce Katz","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/4c65b2117dbb672d0bda009f0367a4721c9271f1f68b1747fb53d7333079d0f1?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4c65b2117dbb672d0bda009f0367a4721c9271f1f68b1747fb53d7333079d0f1?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4c65b2117dbb672d0bda009f0367a4721c9271f1f68b1747fb53d7333079d0f1?s=96&d=mm&r=g","caption":"Bruce Katz"},"url":"https:\/\/paju.org\/fr\/author\/chadi\/"}]}},"_links":{"self":[{"href":"https:\/\/paju.org\/fr\/wp-json\/wp\/v2\/posts\/251199","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/paju.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/paju.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/paju.org\/fr\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/paju.org\/fr\/wp-json\/wp\/v2\/comments?post=251199"}],"version-history":[{"count":3,"href":"https:\/\/paju.org\/fr\/wp-json\/wp\/v2\/posts\/251199\/revisions"}],"predecessor-version":[{"id":251203,"href":"https:\/\/paju.org\/fr\/wp-json\/wp\/v2\/posts\/251199\/revisions\/251203"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/paju.org\/fr\/wp-json\/wp\/v2\/media\/251196"}],"wp:attachment":[{"href":"https:\/\/paju.org\/fr\/wp-json\/wp\/v2\/media?parent=251199"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/paju.org\/fr\/wp-json\/wp\/v2\/categories?post=251199"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/paju.org\/fr\/wp-json\/wp\/v2\/tags?post=251199"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}